{"id":3622,"date":"2024-11-15T17:43:09","date_gmt":"2024-11-15T22:43:09","guid":{"rendered":"https:\/\/www.caminosalkantay.com\/blog\/?p=3622"},"modified":"2024-11-15T19:19:22","modified_gmt":"2024-11-16T00:19:22","slug":"el-arte-del-quipu","status":"publish","type":"post","link":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/","title":{"rendered":"El Arte del Quipu"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-que-es-un-quipu\">\u00bfQu\u00e9 es un quipu?<\/h2>\n\n\n\n<p>Tal vez nunca hayas o\u00eddo hablar de \u00e9l, y si no fuera por este blog, jam\u00e1s sabr\u00edas qu\u00e9 son esas cuerdas coloridas que ver\u00e1s a la venta en algunas de las muchas tiendas de artesan\u00eda en Cusco. De hecho, la ciudad ofrece una variedad tan amplia de souvenirs que los quipus pueden pasar desapercibidos. Sin embargo, una vez que conozcas su importancia y valor como artefacto hist\u00f3rico, ver\u00e1s esta importante arte inca con otros ojos.<\/p>\n\n\n\n<p>Quipu o Quipo, en el idioma quechua, khipu, est\u00e1 descrito en el diccionario como un instrumento utilizado en el pasado por los incas y otras culturas antiguas de los Andes, con fines de comunicaci\u00f3n, pero que tambi\u00e9n serv\u00eda como registro contable y mnemot\u00e9cnico.<\/p>\n\n\n\n<p>Los quipus eran la herramienta que usaban para registrar sus escritos, historias e incluso su m\u00fasica en el idioma quechua. Tambi\u00e9n ayudaban en la contabilidad del ganado y de las personas. En el centro del imperio de Cusco, cualquier comunicaci\u00f3n que deb\u00eda llegar r\u00e1pidamente al emperador se hac\u00eda gracias a ellos.<\/p>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents anchor-links\"><ul><li><a href=\"#h-que-es-un-quipu\" data-level=\"2\">\u00bfQu\u00e9 es un quipu?<\/a><\/li><li><a href=\"#h-el-milagro-de-los-quipus-sobrevivientes\" data-level=\"2\">El milagro de los quipus sobrevivientes<\/a><\/li><li><a href=\"#h-los-quipus-hoy-en-dia\" data-level=\"2\">Los quipus hoy en d\u00eda<\/a><\/li><li><a href=\"#h-sus-caracteristicas\" data-level=\"2\">Sus caracter\u00edsticas<\/a><\/li><li><a href=\"#h-quienes-fueron-los-chasquis\" data-level=\"2\">\u00bfQui\u00e9nes fueron los chasquis?<\/a><\/li><li><a href=\"#h-y-los-khipu-kamayuq\" data-level=\"2\">\u00bfY los khipu kamayuq?<\/a><\/li><li><a href=\"#h-quipu-puedes-tener-el-tuyo\" data-level=\"2\">Quipu, \u00a1puedes tener el tuyo!<\/a><\/li><li><a href=\"#h-te-puede-interesar\" data-level=\"2\">Te puede interesar<\/a><\/li><\/ul><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/El-Quipu-1024x683.jpg\" alt=\"El Quipu\" class=\"wp-image-3627\"\/><figcaption class=\"wp-element-caption\">El Quipu<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-milagro-de-los-quipus-sobrevivientes\">El milagro de los quipus sobrevivientes<\/h2>\n\n\n\n<p>Cuando Atahualpa ascendi\u00f3 al trono, uno de sus principales objetivos era erradicar la historia inca, junto con la destrucci\u00f3n de los relatos hist\u00f3ricos relacionados con el reinado de su rival y medio hermano, Hu\u00e1scar. Este nuevo reinado elimin\u00f3 todos los quipus que encontr\u00f3.<\/p>\n\n\n\n<p>Del mismo modo, la conquista espa\u00f1ola persigui\u00f3 los quipus que a\u00fan exist\u00edan, ya que no lograban descifrar los mensajes contenidos en ellos. Y como resultado de estas persecuciones, \u00a1es incre\u00edble que a\u00fan queden cientos de quipus que han sobrevivido hasta hoy!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-los-quipus-hoy-en-dia\">Los quipus hoy en d\u00eda<\/h2>\n\n\n\n<p>Actualmente, imag\u00ednate, el quipu a\u00fan es utilizado por algunos pueblos andinos y de Am\u00e9rica del Sur, especialmente por pastores de ovejas y cabras como m\u00e9todo para registrar sus reba\u00f1os. En ciudades como Cusco y alrededores, aparece como adorno decorando las paredes de las habitaciones de varios hoteles.<\/p>\n\n\n\n<p>Debo confesar que la primera vez que vi un quipu, en la ciudad de Pisac, me extra\u00f1aron esos hilos colgados sobre mi cabecera, pero en el apuro del viaje no tuve tiempo para investigar qu\u00e9 era. Lo que no imaginaba era que estaba frente a uno de los mayores artefactos del Imperio Inca, el primer ordenador, el primer peri\u00f3dico creado por ellos, la forma m\u00e1s rudimentaria de comunicaci\u00f3n desarrollada por una de las culturas m\u00e1s fascinantes de la humanidad: una herramienta que, en su \u00e9poca, cumpli\u00f3 con maestr\u00eda su funci\u00f3n.<\/p>\n\n\n\n<p>Cuando hablamos de las complejas sociedades precolombinas, es dif\u00edcil atribuirle a simples cordones de lana de llama, oveja o algod\u00f3n el importante papel de comunicar los mensajes m\u00e1s importantes al emperador.<\/p>\n\n\n\n<p>Los quipus s\u00f3lo est\u00e1n presentes hoy gracias a la forma en que la cultura andina ha preservado sus tradiciones, y por eso mantienen su originalidad, siendo id\u00e9nticos a los del pasado. La mayor\u00eda de los quipus a la venta hoy contienen los meses del a\u00f1o y son, en su mayor\u00eda, coloridos.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/Los-quipus-hoy-en-dia-1024x577.jpg\" alt=\"Los quipus hoy en d\u00eda\" class=\"wp-image-3632\"\/><figcaption class=\"wp-element-caption\">Los quipus<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sus-caracteristicas\">Sus caracter\u00edsticas<\/h2>\n\n\n\n<p>Los cordones se produc\u00edan, y siguen produci\u00e9ndose, con lana de llama o alpaca, o de algod\u00f3n. Pueden ser de colores o no, y sus colores indican el \u00edtem que se est\u00e1 contando. Para cada actividad (agricultura, ej\u00e9rcito, ingenier\u00eda, etc.) exist\u00eda una simbolog\u00eda propia de colores. La coloraci\u00f3n es completamente natural, extra\u00edda de hojas e insectos.<\/p>\n\n\n\n<p>Pueden estar adornados con huesos y plumas, o no. Cada nudo tiene un significado o mensaje distinto. La posici\u00f3n del nudo, as\u00ed como su cantidad, indican valores num\u00e9ricos seg\u00fan un sistema decimal. En cada cord\u00f3n puede haber uno o m\u00e1s nudos, o ninguno, o uno en la punta y otro en la base.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"513\" src=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/Quipu-1024x513.jpg\" alt=\"Quipu\" class=\"wp-image-3628\"\/><figcaption class=\"wp-element-caption\">Quipu<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quienes-fueron-los-chasquis\">\u00bfQui\u00e9nes fueron los chasquis?<\/h2>\n\n\n\n<p>Los mensajeros encargados de transportar los quipus se llamaban chasquis. Eran hombres que recorr\u00edan a pie varios kil\u00f3metros de caminos incas, a la mayor velocidad posible, con el objetivo de llevar el quipu al siguiente puesto de mensajeros, donde otro chasqui, descansado, continuaba la carrera hasta que finalmente la informaci\u00f3n llegaba a manos del emperador.<\/p>\n\n\n\n<p>Debido a la falta de un alfabeto escrito, los quipus representaban un m\u00e9todo simple y pr\u00e1ctico de transporte: ligeros, flexibles y con un alto grado de precisi\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/Los-chasquis-1024x683.jpg\" alt=\"Los chasquis\" class=\"wp-image-3629\"\/><figcaption class=\"wp-element-caption\">Los chasquis<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-y-los-khipu-kamayuq\">\u00bfY los khipu kamayuq?<\/h2>\n\n\n\n<p>En la capital inca, Cusco, los especialistas en quipus, llamados khipu kamayuq, eran profesionales que, adem\u00e1s de mantener registros usando los nudos, tambi\u00e9n los utilizaban como \u201cayuda-memoria\u201d para contar historias, mitos y poemas de las tradiciones incas, as\u00ed como las conquistas imperiales y la genealog\u00eda real.<\/p>\n\n\n\n<p>Eran excelentes para registrar los censos de las provincias: el n\u00famero total de personas, g\u00e9nero (masculino y femenino), ni\u00f1os, solteros y casados, etc. Otro tipo de informaci\u00f3n registrada en el quipu inclu\u00eda cuentas, almacenes, impuestos (pagados en especie), ganado, medidas de tierras, ej\u00e9rcitos y equipamiento b\u00e9lico, astronom\u00eda y calendarios, adem\u00e1s de peque\u00f1as descripciones orales hechas por los mensajeros postales, los chasquis.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/los-khipu-kamayuq-1024x683.jpg\" alt=\"Los khipu kamayuq\" class=\"wp-image-3626\"\/><figcaption class=\"wp-element-caption\">Los khipu kamayuq<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quipu-puedes-tener-el-tuyo\">Quipu, \u00a1puedes tener el tuyo!<\/h2>\n\n\n\n<p>Por lo tanto, querido lector, cuando te encuentres con un quipu humildemente situado en los puestos de artesan\u00eda de las calles de Cusco, haz una reverencia mental: est\u00e1s ante lo que puede considerarse uno de los artefactos originales m\u00e1s importantes de la era inca, a la venta en la plaza p\u00fablica por un precio irrisorio. Es original, ya que sigue siendo confeccionado por las manos de sus propios descendientes. Creemos que es uno de los recuerdos m\u00e1s significativos que puedes llevar a casa. \u00a1Tus amigos y familiares quedar\u00e1n asombrados!<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/Quipu-@deco.taty_.jpg\" alt=\"Quipu | @deco.taty\" class=\"wp-image-3630\"\/><figcaption class=\"wp-element-caption\">Quipu | @deco.taty<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/Quipu-@numbra_fiberart.jpg\" alt=\"Quipu | @numbra_fiberart\" class=\"wp-image-3631\"\/><figcaption class=\"wp-element-caption\">Quipu | @numbra_fiberart<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-te-puede-interesar\">Te puede interesar<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.caminosalkantay.com\/blog\/inti-raymi-la-fiesta-mayor-del-cusco\/\">Inti Raymi: La fiesta del Sol<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.caminosalkantay.com\/blog\/frases-en-quechua-el-idioma-antiguo-de-los-incas\/\">Frases en Quechua: El idioma antiguo de los Incas<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.caminosalkantay.com\/blog\/qeswachaka-el-ultimo-puente-inca\/\">Q\u2019eswachaka: El \u00daltimo Puente Inca<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.caminosalkantay.com\/blog\/lo-mejor-para-hacer-en-cusco\/\">Lo mejor para hacer en Cusco<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.caminosalkantay.com\/blog\/donde-alojarse-en-cusco\/\">\u00bfD\u00f3nde alojarse en Cusco?<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.caminosalkantay.com\/blog\/donde-comer-en-cusco-2025-lo-mejor-de-cusco\/\">Donde comer en Cusco 2025, lo mejor de Cusco<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.caminosalkantay.com\/blog\/temporada-de-lluvias-en-cusco-todo-lo-que-debes-saber\/\">Temporada de lluvias en Cusco: Todo lo que debes saber<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list lang\">\n<li class=\"en\"><a href=\"https:\/\/www.salkantaytrekking.com\/blog\/the-art-of-the-quipu\/\">EN<\/a><\/li>\n\n\n\n<li class=\"pt\"><a href=\"https:\/\/www.salkantaytrilha.com\/blog\/a-arte-do-quipo\/\">PT<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es un quipu? Tal vez nunca hayas o\u00eddo hablar de \u00e9l, y si no fuera por este blog, jam\u00e1s sabr\u00edas qu\u00e9 son esas cuerdas coloridas que ver\u00e1s a la venta en algunas de las muchas tiendas de artesan\u00eda en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,850,566],"tags":[849,851,852,848],"class_list":["post-3622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cusco","category-khipu","category-tradiciones","tag-khipu","tag-los-chasquis","tag-los-khipu-kamayuq","tag-que-es-un-quipu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Arte del Quipu | Informaci\u00f3n de Viajes<\/title>\n<meta name=\"description\" content=\"Descubre la importancia de los quipus en la historia inca y su valor como artefacto hist\u00f3rico. Conoce c\u00f3mo se utilizaban para la comunicaci\u00f3n y el registro contable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Arte del Quipu\" \/>\n<meta property=\"og:description\" content=\"Descubre la importancia de los quipus en la historia inca y su valor como artefacto hist\u00f3rico. Conoce c\u00f3mo se utilizaban para la comunicaci\u00f3n y el registro contable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/\" \/>\n<meta property=\"og:site_name\" content=\"Informaci\u00f3n de Viajes a Machu Picchu | Cusco | Per\u00fa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SalkantayTrekking\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-15T22:43:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-16T00:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/El-Arte-del-Quipu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1873\" \/>\n\t<meta property=\"og:image:height\" content=\"1249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camino Salkantay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@salkantayperu\" \/>\n<meta name=\"twitter:site\" content=\"@salkantayperu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camino Salkantay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/\"},\"author\":{\"name\":\"Camino Salkantay\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#\\\/schema\\\/person\\\/53071c800d0ee3cb98d89c6dffbc171f\"},\"headline\":\"El Arte del Quipu\",\"datePublished\":\"2024-11-15T22:43:09+00:00\",\"dateModified\":\"2024-11-16T00:19:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/\"},\"wordCount\":1087,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/El-Arte-del-Quipu.jpg\",\"keywords\":[\"khipu\",\"Los chasquis\",\"Los khipu kamayuq\",\"Qu\u00e9 es un quipu\"],\"articleSection\":[\"Cusco\",\"khipu\",\"Tradiciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#respond\"]}],\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/\",\"url\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/\",\"name\":\"El Arte del Quipu | Informaci\u00f3n de Viajes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/El-Arte-del-Quipu.jpg\",\"datePublished\":\"2024-11-15T22:43:09+00:00\",\"dateModified\":\"2024-11-16T00:19:22+00:00\",\"description\":\"Descubre la importancia de los quipus en la historia inca y su valor como artefacto hist\u00f3rico. Conoce c\u00f3mo se utilizaban para la comunicaci\u00f3n y el registro contable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/El-Arte-del-Quipu.jpg\",\"contentUrl\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/El-Arte-del-Quipu.jpg\",\"width\":1873,\"height\":1249,\"caption\":\"El Arte del Quipu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/el-arte-del-quipu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Arte del Quipu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/\",\"name\":\"Informaci\u00f3n de Viajes a Machu Picchu | Cusco | Per\u00fa\",\"description\":\"Informaci\u00f3n de Viajes a Machu Picchu | Cusco | Per\u00fa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#organization\",\"name\":\"Camino Salkantay\",\"url\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/salkantaytrekking-logo-300x128-1.png\",\"contentUrl\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/salkantaytrekking-logo-300x128-1.png\",\"width\":300,\"height\":128,\"caption\":\"Camino Salkantay\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalkantayTrekking\\\/\",\"https:\\\/\\\/x.com\\\/salkantayperu\",\"https:\\\/\\\/www.tumblr.com\\\/salkantay-trek\",\"https:\\\/\\\/www.instagram.com\\\/salkantaytrekking\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/salkantaytrekking\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/salkantay-trekking\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\\\/#\\\/schema\\\/person\\\/53071c800d0ee3cb98d89c6dffbc171f\",\"name\":\"Camino Salkantay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b41678a33c57a2bf0032b7c254611fc97caffd94ade0663405b364d1c0177d1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b41678a33c57a2bf0032b7c254611fc97caffd94ade0663405b364d1c0177d1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b41678a33c57a2bf0032b7c254611fc97caffd94ade0663405b364d1c0177d1d?s=96&d=mm&r=g\",\"caption\":\"Camino Salkantay\"},\"sameAs\":[\"https:\\\/\\\/www.caminosalkantay.com\\\/blog\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Arte del Quipu | Informaci\u00f3n de Viajes","description":"Descubre la importancia de los quipus en la historia inca y su valor como artefacto hist\u00f3rico. Conoce c\u00f3mo se utilizaban para la comunicaci\u00f3n y el registro contable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/","og_locale":"es_ES","og_type":"article","og_title":"El Arte del Quipu","og_description":"Descubre la importancia de los quipus en la historia inca y su valor como artefacto hist\u00f3rico. Conoce c\u00f3mo se utilizaban para la comunicaci\u00f3n y el registro contable.","og_url":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/","og_site_name":"Informaci\u00f3n de Viajes a Machu Picchu | Cusco | Per\u00fa","article_publisher":"https:\/\/www.facebook.com\/SalkantayTrekking\/","article_published_time":"2024-11-15T22:43:09+00:00","article_modified_time":"2024-11-16T00:19:22+00:00","og_image":[{"width":1873,"height":1249,"url":"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/El-Arte-del-Quipu.jpg","type":"image\/jpeg"}],"author":"Camino Salkantay","twitter_card":"summary_large_image","twitter_creator":"@salkantayperu","twitter_site":"@salkantayperu","twitter_misc":{"Escrito por":"Camino Salkantay","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#article","isPartOf":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/"},"author":{"name":"Camino Salkantay","@id":"https:\/\/www.caminosalkantay.com\/blog\/#\/schema\/person\/53071c800d0ee3cb98d89c6dffbc171f"},"headline":"El Arte del Quipu","datePublished":"2024-11-15T22:43:09+00:00","dateModified":"2024-11-16T00:19:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/"},"wordCount":1087,"commentCount":0,"publisher":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/El-Arte-del-Quipu.jpg","keywords":["khipu","Los chasquis","Los khipu kamayuq","Qu\u00e9 es un quipu"],"articleSection":["Cusco","khipu","Tradiciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#respond"]}],"accessibilityFeature":["tableOfContents"]},{"@type":"WebPage","@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/","url":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/","name":"El Arte del Quipu | Informaci\u00f3n de Viajes","isPartOf":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#primaryimage"},"image":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/El-Arte-del-Quipu.jpg","datePublished":"2024-11-15T22:43:09+00:00","dateModified":"2024-11-16T00:19:22+00:00","description":"Descubre la importancia de los quipus en la historia inca y su valor como artefacto hist\u00f3rico. Conoce c\u00f3mo se utilizaban para la comunicaci\u00f3n y el registro contable.","breadcrumb":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#primaryimage","url":"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/El-Arte-del-Quipu.jpg","contentUrl":"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2024\/11\/El-Arte-del-Quipu.jpg","width":1873,"height":1249,"caption":"El Arte del Quipu"},{"@type":"BreadcrumbList","@id":"https:\/\/www.caminosalkantay.com\/blog\/el-arte-del-quipu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.caminosalkantay.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El Arte del Quipu"}]},{"@type":"WebSite","@id":"https:\/\/www.caminosalkantay.com\/blog\/#website","url":"https:\/\/www.caminosalkantay.com\/blog\/","name":"Informaci\u00f3n de Viajes a Machu Picchu | Cusco | Per\u00fa","description":"Informaci\u00f3n de Viajes a Machu Picchu | Cusco | Per\u00fa","publisher":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caminosalkantay.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.caminosalkantay.com\/blog\/#organization","name":"Camino Salkantay","url":"https:\/\/www.caminosalkantay.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.caminosalkantay.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2023\/05\/salkantaytrekking-logo-300x128-1.png","contentUrl":"https:\/\/www.caminosalkantay.com\/blog\/wp-content\/uploads\/2023\/05\/salkantaytrekking-logo-300x128-1.png","width":300,"height":128,"caption":"Camino Salkantay"},"image":{"@id":"https:\/\/www.caminosalkantay.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalkantayTrekking\/","https:\/\/x.com\/salkantayperu","https:\/\/www.tumblr.com\/salkantay-trek","https:\/\/www.instagram.com\/salkantaytrekking\/","https:\/\/www.pinterest.com\/salkantaytrekking\/","https:\/\/www.linkedin.com\/company\/salkantay-trekking"]},{"@type":"Person","@id":"https:\/\/www.caminosalkantay.com\/blog\/#\/schema\/person\/53071c800d0ee3cb98d89c6dffbc171f","name":"Camino Salkantay","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b41678a33c57a2bf0032b7c254611fc97caffd94ade0663405b364d1c0177d1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b41678a33c57a2bf0032b7c254611fc97caffd94ade0663405b364d1c0177d1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b41678a33c57a2bf0032b7c254611fc97caffd94ade0663405b364d1c0177d1d?s=96&d=mm&r=g","caption":"Camino Salkantay"},"sameAs":["https:\/\/www.caminosalkantay.com\/blog"]}]}},"_links":{"self":[{"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/posts\/3622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/comments?post=3622"}],"version-history":[{"count":4,"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/posts\/3622\/revisions"}],"predecessor-version":[{"id":3692,"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/posts\/3622\/revisions\/3692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/media\/3636"}],"wp:attachment":[{"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/media?parent=3622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/categories?post=3622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caminosalkantay.com\/blog\/wp-json\/wp\/v2\/tags?post=3622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}